{"id":666,"date":"2019-11-28T16:32:31","date_gmt":"2019-11-28T15:32:31","guid":{"rendered":"http:\/\/klauskunze.com\/blog\/?p=666"},"modified":"2019-12-01T12:06:46","modified_gmt":"2019-12-01T11:06:46","slug":"die-macht-des-symbolischen","status":"publish","type":"post","link":"http:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/","title":{"rendered":"Die Macht des Symbolischen"},"content":{"rendered":"\n<p>Die Chancen rationaler Politik\nstehen schlecht. Die Massen-Medien-Demokratie belohnt es nicht, Interessen\nrational vorzutragen und zu vertreten. Ihre Spielregeln beg\u00fcnstigen Str\u00f6mungen,\ndie sich emotional geben und diese Gef\u00fchle in Form bestimmter Symbole gie\u00dfen. <\/p>\n\n\n\n<p><em>Symbolon<\/em>\nnannten schon die antiken Griechen ein Wiedererkennungszeichen unter Freunden. Mit\ndem Verb <em>symballein<\/em> bezeichneten sie\nes, wenn ein zerbrochenes St\u00fcck wie ein Ring wieder aneinandergehalten wurde.\nPa\u00dften die Teile zueinander, hatten sich die Richtigen gefunden. Symbole wurden\nzum festen Bestandteil menschlicher Kultur vom urchristlichen Fisch bis zum\nmodernen Smiley. Sie symbolisieren zusammengeh\u00f6rende Menschen, aber auch ganze\nW\u00f6rter, S\u00e4tze, Gef\u00fchle oder Glaubensbekenntnisse bis hin zu komplexen\nWeltanschauungen.<\/p>\n\n\n\n<p>In unserem Medienalltag haben sie das gesprochene\nWort verdr\u00e4ngt und ersetzt. Das gilt \u00fcberall da, wo eine Sendung produziert\nwird, um Menschen zu beeinflussen: bei der Produktreklame, in\nNachrichtensendungen, in Vorabendserien. Bildsymbole erkennt jeder sofort als\nSymbol. Wer in der Sportschau das Symbol eines konkurrierenden Vereins sieht, schaltet\ninnerlich schnell auf Abwehr. <\/p>\n\n\n\n<p>Viel wirksamer, ja geradezu heimt\u00fcckisch wirken nicht\nbildliche Symbole. Das EU-Parlament hat \u201esymbolisch\u201c den \u201eKlimanotstand\u201c\nausgerufen, ein Minister legt \u201esymbolisch\u201c einen Kranz nieder, man bildet eine\nLichterkette, man ehrt am Volkstrauertag die Toten. Einen festen Ritus erkennen\nwir noch gut als Symbol.<\/p>\n\n\n\n<p>Der politische Betrieb ist weitgehend ritualisiert\nund bedient sich feststehender Wortsymbole. Das sind so weitl\u00e4ufig formulierte Begriffe,\nda\u00df sich eigentlich jeder etwas verschiedenes darunter vorstellen kann. Wenn\ndie kommunistische SED fr\u00fcher die Parole ausgab: \u201eVorw\u00e4rts zum Sozialismus!\u201c,\nbildete dieser Begriff f\u00fcr sich allein bereits ein Symbol. Er stand f\u00fcr ein\nkomplexes Gedankensystem, in dem die F\u00fchrung des Volkes durch die SED einen\nzentralen Platz einnahm. <\/p>\n\n\n\n<p>Einem diffus klingenden Wortsymbol einen eindeutigen Kern zu geben, ist ein Akt der Machtaus\u00fcbung. Die Macht hat, wer den Menschen immer dieselben Wortsymbole und Parolen einh\u00e4mmert und \u00fcber ihren konkreten Inhalt bestimmt. Dann wird nicht mehr dar\u00fcber diskutiert, was \u201eSozialismus\u201c und all die anderen h\u00fcbschen Wortsymbole alles bedeuten k\u00f6nnten. Es ist bereits reglementiert und wird vom Staats-Propaganda-Fernsehen t\u00e4glich tausendfach einge\u00fcbt.<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-large\"><img decoding=\"async\" src=\"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg\" alt=\"\" class=\"wp-image-669\"\/><figcaption>Die Macht der Symbole:<br>Bildmedien haben das Druckmedium symbolisch zur Strecke gebracht (A.Paul Weber)<\/figcaption><\/figure>\n\n\n\n<p>Wortsymbole sind wie Etiketten, die man anderen\nMenschen aufkleben kann, um sie damit zu kennzeichnen. Ein unsicheres Leben\nhatten im Mittelalter Prostituierte und Juden, oft symbolisch durch farbige\nAbzeichen beziehungsweise spitze Kopfbedeckungen gekennzeichnet. Auf Kleidung\naufn\u00e4hbare Symbole sind veraltet. Wer seinen Gegner heute stigmatisieren will,\nbenutzt immer dieselbe Wortsymbole und Stereotype und heftet sie dem anderen an,\nder sie genausowenig mehr loswerden kann wie einen pickligen Ausschlag. <\/p>\n\n\n\n<p>Zum Ketzer wurde ein gl\u00e4ubiger Christ im Mittelalter\nnicht schon durch ketzerische Ansichten, sondern, indem er zum Ketzer erkl\u00e4rt\nwurde. Die Acht konnte \u00fcber jemanden verh\u00e4ngt werden, der angeblich v\u00f6llig\nau\u00dferhalb des Gesetzes stand. Heute findet gesellschaftliche \u00c4chtung durch\nWortsymbole statt. Das derzeitige Universalsymbol f\u00fcr diese Art \u00c4chtung ist das\nN-Wort. Wie ein Dietrich in jedes Schlo\u00df pa\u00dft, kann jeder dieses Wort beliebig\njedem anheften. Es soll dem Publikum das Nachdenken ersparen, soll\nstigmatisieren, soll ausgrenzen.<\/p>\n\n\n\n<p>Mit Wortsymbolen schm\u00fccken sich die Guten, mit\nWortsymbolen stigmatisieren sie die B\u00f6sen. Der Welt der Stigmatisierer ist so schlicht\nwie ein Paintballspiel. Es gen\u00fcgt, den Gegner mit etwas Farbe symbolisch zu\nbekleckern. Etwas h\u00e4ngen bleibt immer.<\/p>\n\n\n\n<p>Die Spielregeln des politischen Machtgewinns und\nMachterhalts beg\u00fcnstigen nicht mehr den, der gute Argumente hat und sie wirksam\nin Worte kleiden kann. Es h\u00f6rt ihm n\u00e4mlich niemand mehr zu. Worten darf man \u201ekeine\nB\u00fchne bieten\u201c und stellt sich lieber symbolisch vor das Veranstaltungslokal, um\ndie Worte zu verhindern. Dabei darf man sicher sein, da\u00df die Medien reflexhaft darauf\nanspringen. Im Fernsehen wird niemand h\u00f6ren, was der verhinderte Redner nicht\nsagen durfte. Er wird aber die sich entfaltende Symbolik der Bilder\nverinnerlichen: Blockierer mit entschlossenen Mienen, Transparente mit\ngutherzigen Parolen, den ganze Ritus einer symbolischen Auff\u00fchrung. <\/p>\n\n\n\n<p>Diese Bildsymbole haften in den K\u00f6pfen von\nMedienkonsumenten. Die ganze symbolische Schau w\u00e4re wirkungslos und in sich\nsinnlos, w\u00fcrde sie nicht medial transportiert. Die Medien ihrerseits sind meistens\nunf\u00e4hig oder unwillig, gesprochene Argumentation zu transportieren und den\nZuschauern nahezubringen. Diese klicken n\u00e4mlich als Medienkonsumenten in\nk\u00fcrzester Zeit auf einen anderen Sender, wenn ihnen geistig zu viel und zu\nlange etwas abverlangt wird. Vom Medienkonsumenten \u00fcber den von Symbolbild zum\nSymbol-O-Ton getriebenen Reporter bis hin zu den Symbole schaffenden Akteuren\nauf der politischen B\u00fchne unterliegen alle denselben Gesetzlichkeiten.<\/p>\n\n\n\n<p>Eine Parole wie ein symbolisches \u201eWir schaffen das!\u201c\nist eing\u00e4ngiger als eine pr\u00e4gnante Argumentation. Lesen ist anstrengender als\nSymbolbilder anzuschauen. Die Verweildauer des Auges auf einem Objekt wird\nk\u00fcrzer. Die Aufmerksamkeitsdauer vieler Menschen sinkt. Sie k\u00f6nnen sich nicht\nmehr so lange auf einen Text konzentrieren. Merken Sie es auch schon?<\/p>\n\n\n\n<p>So konnte das Zeitalter der Symbole anbrechen. Da\nw\u00e4scht ein Papst drei Landstreichern symbolisch die F\u00fc\u00dfe. Die scheinbare Demut\nund N\u00e4chstenliebe versinnbildlicht seine Deutungshoheit dar\u00fcber, was Demut ist\nund was N\u00e4chstenliebe erfordert. Ein neuer Minister ruft auf zum \u201eKampf gegen\nRechts\u201c und erhebt damit symbolisch den Machtanpruch, beh\u00f6rdlich verbindlich zu\nbestimmen, was rechts ist und welche Konsequenzen das im einzelnen haben soll.\nDer Bundestag debattiert dar\u00fcber, symbolisch als \u201eKinderrechte\u201c ins Grundgesetz\nzu schreiben, was Kinder an Grund- und Menschenrechten sowieso schon haben. Die\nKoalition zankt sich dar\u00fcber, wieviel Geld sie den Steuerzahlern aus der rechten\nTasche ziehen soll, um sie als Sozialleistungen in die linke zu stecken. Jede\nPartei m\u00f6chte sich dem Publikum n\u00e4mlich symbolisch als diejenige darstellen,\ndie \u201ef\u00fcr Gerechtigkeit\u201c eintritt.<\/p>\n\n\n\n<p>Politik funktioniert nicht mehr nach Regeln argumentativer, interessengeleiteter Rationalit\u00e4t, sondern danach, wer die passenden, emotional aufgeladenen Bild- und Wortsymbole allgemein durchsetzt und so vielleicht die n\u00e4chste Wahl gewinnt. Darum spielt reales Handeln eine geringere Rolle als &#8222;Zeichen zu setzen&#8220;. Nehme ich allerdings blo\u00df mal eben einen Teller und ein Abtrockentuch zur Hand, um symbolisch meinen guten Willen zu zeigen und ein Zeichen zu setzen, bin ich ein schlechter K\u00fcchenhelfer. Von den Zeichen setzenden Haltungspolitikern sieht man gew\u00f6hnlich nichts mehr, nachdem die Kameras ausgeschaltet sind.<\/p>\n\n\n\n<p>Derweil sondern sich Bev\u00f6lkerungskreise unter\nverschiedenen Symbolen voneinander ab, igeln sich ein in Echokammern und\nmedialen Seifenblasen ihres guten Gewissens. Sie kuscheln sich gern zusammen in\nInternetforen Gleichgesinnter. Hier wollen sie nicht gest\u00f6rt werden durch\nMenschen mit anderen, abweichenden Ansichten. Die Verwendung emotionaler\nPa\u00dfw\u00f6rter und ideologischer Schl\u00fcsselw\u00f6rter symbolisiert die Zugeh\u00f6rigkeit zum\njeweiligen \u201eWir\u201c. Wenn man die anderen gar nicht mehr h\u00f6rt und sieht, wei\u00df man\nnat\u00fcrlich: \u201eWir sind mehr!\u201c<\/p>\n\n\n\n<p>Der politische Kampf hat sich dahin verlagert, wo Wortsymbole geschmiedet und den Gegnern aufgezwungen werden und wo die des Gegners unterdr\u00fcckt werden. Es geht schon lange nicht mehr um rationale Erfassung zum Beispiel der deutschen Interessenlage, wenn man mal eben \u00fcber eine Million Fremder ins Land l\u00e4\u00dft. Die politische Auseinandersetzung wird gef\u00fchrt, indem Wortsymbole wie \u201eAusl\u00e4nder\u201c, \u201eillegaler Einwanderer\u201c und dergleichen vermieden und durch Wortsymbole wie \u201eFl\u00fcchtling\u201c oder \u201eMigrant\u201c ersetzt werden. Die Entscheidung \u00fcber Masseneinwanderung mutiert von einer &#8211; denkm\u00f6glichen &#8211; interessengeleiteten, rationalen Entscheidung zu einem symbolischen Akt der eigenen Moralit\u00e4t. Schlie\u00dflich ist auch das Selbstgef\u00fchl, moralisch zu sein, eine symbolische Eigenpositionierung: in einem Gedankenkosmos, der zwischen den strahlenden H\u00f6hen des Guten und den schwarzen Abgr\u00fcnden des B\u00f6sen keine Graut\u00f6ne erkennt.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Auch publiziert auf <a href=\"https:\/\/wir-selbst.com\/2019\/12\/01\/die-macht-des-symbolischen\/\">Wir selbst 1.12.2019<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Chancen rationaler Politik stehen schlecht. Die Massen-Medien-Demokratie belohnt es nicht, Interessen rational vorzutragen und zu vertreten. Ihre Spielregeln beg\u00fcnstigen Str\u00f6mungen, die sich emotional geben und diese Gef\u00fchle in Form bestimmter Symbole gie\u00dfen. Symbolon nannten schon die antiken Griechen ein Wiedererkennungszeichen unter Freunden. Mit dem Verb symballein bezeichneten sie es, wenn ein zerbrochenes St\u00fcck wie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[1,20,17],"tags":[],"class_list":["post-666","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-philosophie","category-politik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Macht des Symbolischen - Klaus Kunze<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Macht des Symbolischen - Klaus Kunze\" \/>\n<meta property=\"og:description\" content=\"Die Chancen rationaler Politik stehen schlecht. Die Massen-Medien-Demokratie belohnt es nicht, Interessen rational vorzutragen und zu vertreten. Ihre Spielregeln beg\u00fcnstigen Str\u00f6mungen, die sich emotional geben und diese Gef\u00fchle in Form bestimmter Symbole gie\u00dfen. Symbolon nannten schon die antiken Griechen ein Wiedererkennungszeichen unter Freunden. Mit dem Verb symballein bezeichneten sie es, wenn ein zerbrochenes St\u00fcck wie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/\" \/>\n<meta property=\"og:site_name\" content=\"Klaus Kunze\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-28T15:32:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-01T11:06:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg\" \/>\n<meta name=\"author\" content=\"Klaus Kunze\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Klaus Kunze\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/\"},\"author\":{\"name\":\"Klaus Kunze\",\"@id\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/#\\\/schema\\\/person\\\/9c091cf30ab68b897db6a517e3c3b11b\"},\"headline\":\"Die Macht des Symbolischen\",\"datePublished\":\"2019-11-28T15:32:31+00:00\",\"dateModified\":\"2019-12-01T11:06:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/\"},\"wordCount\":1240,\"commentCount\":1,\"publisher\":{\"@id\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/#\\\/schema\\\/person\\\/9c091cf30ab68b897db6a517e3c3b11b\"},\"image\":{\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Zur-Strecke-gebracht-a-1024x845.jpg\",\"articleSection\":{\"1\":\"Philosophie\",\"2\":\"Politik\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/\",\"url\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/\",\"name\":\"Die Macht des Symbolischen - Klaus Kunze\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Zur-Strecke-gebracht-a-1024x845.jpg\",\"datePublished\":\"2019-11-28T15:32:31+00:00\",\"dateModified\":\"2019-12-01T11:06:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Zur-Strecke-gebracht-a-1024x845.jpg\",\"contentUrl\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Zur-Strecke-gebracht-a-1024x845.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/klauskunze.com\\\/blog\\\/2019\\\/11\\\/28\\\/die-macht-des-symbolischen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Macht des Symbolischen\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/\",\"name\":\"Klaus Kunze\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/#\\\/schema\\\/person\\\/9c091cf30ab68b897db6a517e3c3b11b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/klauskunze.com\\\/blog\\\/#\\\/schema\\\/person\\\/9c091cf30ab68b897db6a517e3c3b11b\",\"name\":\"Klaus Kunze\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g\",\"caption\":\"Klaus Kunze\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g\"},\"sameAs\":[\"http:\\\/\\\/KlausKunze.com\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/KlausKunze3\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Macht des Symbolischen - Klaus Kunze","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/","og_locale":"de_DE","og_type":"article","og_title":"Die Macht des Symbolischen - Klaus Kunze","og_description":"Die Chancen rationaler Politik stehen schlecht. Die Massen-Medien-Demokratie belohnt es nicht, Interessen rational vorzutragen und zu vertreten. Ihre Spielregeln beg\u00fcnstigen Str\u00f6mungen, die sich emotional geben und diese Gef\u00fchle in Form bestimmter Symbole gie\u00dfen. Symbolon nannten schon die antiken Griechen ein Wiedererkennungszeichen unter Freunden. Mit dem Verb symballein bezeichneten sie es, wenn ein zerbrochenes St\u00fcck wie [&hellip;]","og_url":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/","og_site_name":"Klaus Kunze","article_published_time":"2019-11-28T15:32:31+00:00","article_modified_time":"2019-12-01T11:06:46+00:00","og_image":[{"url":"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg","type":"","width":"","height":""}],"author":"Klaus Kunze","twitter_misc":{"Verfasst von":"Klaus Kunze","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#article","isPartOf":{"@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/"},"author":{"name":"Klaus Kunze","@id":"http:\/\/klauskunze.com\/blog\/#\/schema\/person\/9c091cf30ab68b897db6a517e3c3b11b"},"headline":"Die Macht des Symbolischen","datePublished":"2019-11-28T15:32:31+00:00","dateModified":"2019-12-01T11:06:46+00:00","mainEntityOfPage":{"@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/"},"wordCount":1240,"commentCount":1,"publisher":{"@id":"http:\/\/klauskunze.com\/blog\/#\/schema\/person\/9c091cf30ab68b897db6a517e3c3b11b"},"image":{"@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#primaryimage"},"thumbnailUrl":"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg","articleSection":{"1":"Philosophie","2":"Politik"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/","url":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/","name":"Die Macht des Symbolischen - Klaus Kunze","isPartOf":{"@id":"http:\/\/klauskunze.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#primaryimage"},"image":{"@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#primaryimage"},"thumbnailUrl":"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg","datePublished":"2019-11-28T15:32:31+00:00","dateModified":"2019-12-01T11:06:46+00:00","breadcrumb":{"@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#primaryimage","url":"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg","contentUrl":"http:\/\/klauskunze.com\/blog\/wp-content\/uploads\/2019\/11\/Zur-Strecke-gebracht-a-1024x845.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/klauskunze.com\/blog\/2019\/11\/28\/die-macht-des-symbolischen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/klauskunze.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Die Macht des Symbolischen"}]},{"@type":"WebSite","@id":"http:\/\/klauskunze.com\/blog\/#website","url":"http:\/\/klauskunze.com\/blog\/","name":"Klaus Kunze","description":"Blog","publisher":{"@id":"http:\/\/klauskunze.com\/blog\/#\/schema\/person\/9c091cf30ab68b897db6a517e3c3b11b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/klauskunze.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"http:\/\/klauskunze.com\/blog\/#\/schema\/person\/9c091cf30ab68b897db6a517e3c3b11b","name":"Klaus Kunze","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g","caption":"Klaus Kunze"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/5cd83cadbada9c331a79952fcca177ed3d3be4c7ad3239b9d934bf84adff15dd?s=96&d=blank&r=g"},"sameAs":["http:\/\/KlausKunze.com","https:\/\/x.com\/https:\/\/twitter.com\/KlausKunze3"]}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/posts\/666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/comments?post=666"}],"version-history":[{"count":7,"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/posts\/666\/revisions"}],"predecessor-version":[{"id":707,"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/posts\/666\/revisions\/707"}],"wp:attachment":[{"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/media?parent=666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/categories?post=666"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/klauskunze.com\/blog\/wp-json\/wp\/v2\/tags?post=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}